{"id":7743,"date":"2020-12-10T02:05:22","date_gmt":"2020-12-10T05:05:22","guid":{"rendered":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html"},"modified":"2021-07-28T14:28:28","modified_gmt":"2021-07-28T17:28:28","slug":"stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss","status":"publish","type":"post","link":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html","title":{"rendered":"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS"},"content":{"rendered":"<p><br \/>\n<\/p>\n<p>O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), homologou acordo entre o Minist\u00e9rio P\u00fablico Federal (MPF) e o Instituto Nacional do Seguro Social (INSS) que prev\u00ea prazos m\u00e1ximos para an\u00e1lises dos processos administrativos relacionados a todos os benef\u00edcios administrados pela autarquia e a avalia\u00e7\u00e3o social nos casos em que o benef\u00edcio dependa da aferi\u00e7\u00e3o da defici\u00eancia do segurado.<\/p>\n<p>A decis\u00e3o, proferida nos autos do Recurso Extraordin\u00e1rio (RE) 1171152, dever\u00e1 ser referendada pelo Plen\u00e1rio do STF, mas j\u00e1 tem efic\u00e1cia imediata. O relator solicitou, com urg\u00eancia, a inclus\u00e3o do processo para a pr\u00f3xima sess\u00e3o virtual de julgamento e o retirou da sistem\u00e1tica da repercuss\u00e3o geral (Tema 1066). O entendimento \u00e9 assinado ainda pelo advogado-geral da Uni\u00e3o, Jos\u00e9 Levi, e pelo defensor p\u00fablico-geral federal, Gabriel Faria Oliveira.<\/p>\n<p><b>Prazos<\/b><\/p>\n<p>O acordo prev\u00ea que todos os prazos n\u00e3o devem ultrapassar 90 dias e podem variar conforme a esp\u00e9cie e o grau de complexidade do benef\u00edcio. Para a realiza\u00e7\u00e3o de per\u00edcias m\u00e9dicas necess\u00e1rias \u00e0 concess\u00e3o inicial de benef\u00edcios previdenci\u00e1rios e assistenciais, \u00e9 definido o prazo m\u00e1ximo de 45 dias ap\u00f3s o seu agendamento e de 90 dias, quando realizadas nas unidades de per\u00edcia m\u00e9dica de dif\u00edcil provimento de servidores.<\/p>\n<p><b>Razoabilidade<\/b><\/p>\n<p>Na avalia\u00e7\u00e3o do ministro Alexandre de Moraes, os prazos s\u00e3o razo\u00e1veis, tendo em vista que a lei n\u00e3o fixa limite de tempo para a concess\u00e3o inicial de benef\u00edcio previdenci\u00e1rio ou assistencial. Al\u00e9m disso, a Lei 8.213\/1991 determina que o primeiro pagamento do benef\u00edcio deve ser efetuado 45 dias ap\u00f3s a apresenta\u00e7\u00e3o da documenta\u00e7\u00e3o necess\u00e1ria \u00e0 sua concess\u00e3o  pelo segurado.<\/p>\n<p>&ldquo;O prazo de m\u00e1ximo de 90 dias atende ao princ\u00edpio da razoabilidade, na medida em que n\u00e3o imp\u00f5e aos segurados espera excessiva, e permite \u00e0 administra\u00e7\u00e3o p\u00fablica adotar as medidas necess\u00e1rias e suficientes \u00e0 correta concess\u00e3o dos benef\u00edcios. Da mesma maneira, considero adequada a previs\u00e3o do acordo que estabelece recomenda\u00e7\u00e3o para que o cumprimento de decis\u00f5es judiciais ocorra em no m\u00e1ximo 90 dias, contados a partir da intima\u00e7\u00e3o do INSS, sendo que, para a implanta\u00e7\u00e3o de tutela de urg\u00eancia, deve-se observar o prazo m\u00e1ximo de 15 dias&rdquo;, disse.<\/p>\n<p><b>Acompanhamento<\/b><\/p>\n<p>Em caso de san\u00e7\u00e3o pelo descumprimento do acordo, o INSS obriga-se a analisar o requerimento administrativo, no prazo de 10 dias, por meio da Central Unificada de Cumprimento Emergencial de Prazos. Um comit\u00ea executivo formado por representantes do INSS, do MPF, da Defensoria P\u00fablica da Uni\u00e3o, da Secretaria de Previd\u00eancia e da Advocacia-Geral da Uni\u00e3o ficar\u00e1 encarregado de fazer o acompanhamento do acordo e estabelecer mecanismos de avalia\u00e7\u00e3o dos indicadores de atendimento. Poder\u00e1, ainda, propor medidas de preven\u00e7\u00e3o e buscar solu\u00e7\u00f5es, quando houver risco de descumprimento das cl\u00e1usulas acordadas.<\/p>\n<p><b>Efeito vinculante<\/b><\/p>\n<p>De acordo com o ministro Alexandre de Moraes, em rela\u00e7\u00e3o \u00e0 extin\u00e7\u00e3o das demandas correlatas, o acordo encerra o processo com resolu\u00e7\u00e3o de m\u00e9rito, com efeitos nacionais, e sua homologa\u00e7\u00e3o judicial tem efeito vinculante sobre as a\u00e7\u00f5es coletivas j\u00e1 ajuizadas que tratem do mesmo tema do RE. As a\u00e7\u00f5es judiciais com decis\u00e3o definitiva t\u00eam seus efeitos limitados \u00e0 data da homologa\u00e7\u00e3o.<\/p>\n<p>O relator frisou que o acordo visa n\u00e3o s\u00f3 a pacificar a controv\u00e9rsia instaurada nos autos, mas sobretudo viabilizar a concess\u00e3o dos benef\u00edcios previdenci\u00e1rios, em tempo razo\u00e1vel, para segmento da popula\u00e7\u00e3o, na sua maioria, em situa\u00e7\u00e3o de vulnerabilidade social e econ\u00f4mica, por\u00e9m sem causar preju\u00edzo \u00e0 administra\u00e7\u00e3o p\u00fablica. Ele apontou, ainda, que a decis\u00e3o \u00e9 de relevante interesse p\u00fablico, principalmente em raz\u00e3o da pandemia da Covid-19, que tem gerado um cen\u00e1rio de incertezas para a popula\u00e7\u00e3o.<\/p>\n<p><b>Origem<\/b><\/p>\n<p>O caso se originou em a\u00e7\u00e3o civil p\u00fablica ajuizada pelo MPF em Santa Catarina. Na primeira inst\u00e2ncia, foi determinado ao INSS a realiza\u00e7\u00e3o das per\u00edcias necess\u00e1rias \u00e0 concess\u00e3o de benef\u00edcios previdenci\u00e1rios e assistenciais no prazo m\u00e1ximo de 15 dias, a contar do requerimento do benef\u00edcio. Caso n\u00e3o fosse observado esse prazo, os benef\u00edcios deveriam ser concedidos ou mantidos at\u00e9 que o segurado fosse submetido \u00e0 per\u00edcia m\u00e9dica.<\/p>\n<p>No exame de apela\u00e7\u00e3o do INSS, o Tribunal Regional Federal da 4&ordf; Regi\u00e3o (TRF-4) excluiu do alcance da decis\u00e3o os benef\u00edcios acident\u00e1rios e fixou o prazo m\u00e1ximo de 45 dias para a realiza\u00e7\u00e3o das per\u00edcias m\u00e9dicas, sob pena de implanta\u00e7\u00e3o autom\u00e1tica do benef\u00edcio requerido, com a possibilidade de utiliza\u00e7\u00e3o do sistema de credenciamento tempor\u00e1rio de peritos m\u00e9dicos. Para questionar o ac\u00f3rd\u00e3o do TRF-4, a autarquia federal interp\u00f4s o recurso extraordin\u00e1rio ao STF.<\/p>\n<p>Leia a <a href=\"http:\/\/www.stf.jus.br\/arquivo\/cms\/noticiaNoticiaStf\/anexo\/RE1171152.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u00edntegra da decis\u00e3o<\/a>.<\/p>\n<p><span style=\"font-size: smaller\">RP\/AD\/\/CF<\/span><\/p>\n<p>Leia mais:<\/p>\n<p>4\/10\/2019 &#8211; <a href=\"http:\/\/portal.stf.jus.br\/noticias\/verNoticiaDetalhe.asp?idConteudo=425492&amp;ori=1\" target=\"_blank\" rel=\"noopener noreferrer\">STF decidir\u00e1 se Justi\u00e7a pode estabelecer prazo para realiza\u00e7\u00e3o de per\u00edcia m\u00e9dica do INSS<\/a><\/p>\n<p><i>Com informa\u00e7\u00f5es da assessoria de imprensa do STF.<\/i><br \/>\n<br \/><br \/>\n<br \/><a href=\"http:\/\/www.stf.jus.br\/portal\/cms\/verNoticiaDetalhe.asp?idConteudo=456875\">Fonte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), homologou acordo entre o Minist\u00e9rio P\u00fablico Federal (MPF) e o Instituto Nacional do Seguro Social (INSS) que prev\u00ea prazos m\u00e1ximos para an\u00e1lises dos processos administrativos relacionados a todos os benef\u00edcios administrados pela autarquia e a avalia\u00e7\u00e3o social nos casos em que o benef\u00edcio dependa da [&hellip;]<\/p>\n","protected":false},"author":3063,"featured_media":2964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15],"tags":[11,10,8,13,9,12,16],"class_list":{"0":"post-7743","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-previdenciario","8":"category-stf","9":"tag-aposentadoria","10":"tag-calculos-previdenciarios","11":"tag-direito-previdenciario","12":"tag-inss","13":"tag-pericia","14":"tag-perito","15":"tag-stf"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS | Portal de Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS | Portal de Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), homologou acordo entre o Minist\u00e9rio P\u00fablico Federal (MPF) e o Instituto Nacional do Seguro Social (INSS) que prev\u00ea prazos m\u00e1ximos para an\u00e1lises dos processos administrativos relacionados a todos os benef\u00edcios administrados pela autarquia e a avalia\u00e7\u00e3o social nos casos em que o benef\u00edcio dependa da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-10T05:05:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-28T17:28:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe MH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe MH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\"},\"author\":{\"name\":\"Equipe MH\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\"},\"headline\":\"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS\",\"datePublished\":\"2020-12-10T05:05:22+00:00\",\"dateModified\":\"2021-07-28T17:28:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\"},\"wordCount\":884,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg\",\"keywords\":[\"aposentadoria\",\"c\u00e1lculos previdenci\u00e1rios\",\"direito previdenci\u00e1rio\",\"inss\",\"per\u00edcia\",\"perito\",\"stf\"],\"articleSection\":[\"Direito Previdenci\u00e1rio\",\"STF\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\",\"name\":\"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS | Portal de Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg\",\"datePublished\":\"2020-12-10T05:05:22+00:00\",\"dateModified\":\"2021-07-28T17:28:28+00:00\",\"author\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg\",\"contentUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mhcalculos.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#website\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/\",\"name\":\"Portal de Not\u00edcias\",\"description\":\"Not\u00edcias e Jurisprud\u00eancia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mhcalculos.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\",\"name\":\"Equipe MH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"caption\":\"Equipe MH\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS | Portal de Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html","og_locale":"pt_BR","og_type":"article","og_title":"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS | Portal de Not\u00edcias","og_description":"O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), homologou acordo entre o Minist\u00e9rio P\u00fablico Federal (MPF) e o Instituto Nacional do Seguro Social (INSS) que prev\u00ea prazos m\u00e1ximos para an\u00e1lises dos processos administrativos relacionados a todos os benef\u00edcios administrados pela autarquia e a avalia\u00e7\u00e3o social nos casos em que o benef\u00edcio dependa da [&hellip;]","og_url":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html","og_site_name":"Portal de Not\u00edcias","article_published_time":"2020-12-10T05:05:22+00:00","article_modified_time":"2021-07-28T17:28:28+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg","type":"image\/jpeg"}],"author":"Equipe MH","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe MH","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#article","isPartOf":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html"},"author":{"name":"Equipe MH","@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d"},"headline":"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS","datePublished":"2020-12-10T05:05:22+00:00","dateModified":"2021-07-28T17:28:28+00:00","mainEntityOfPage":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html"},"wordCount":884,"commentCount":0,"image":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage"},"thumbnailUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg","keywords":["aposentadoria","c\u00e1lculos previdenci\u00e1rios","direito previdenci\u00e1rio","inss","per\u00edcia","perito","stf"],"articleSection":["Direito Previdenci\u00e1rio","STF"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html","url":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html","name":"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS | Portal de Not\u00edcias","isPartOf":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage"},"image":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage"},"thumbnailUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg","datePublished":"2020-12-10T05:05:22+00:00","dateModified":"2021-07-28T17:28:28+00:00","author":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d"},"breadcrumb":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#primaryimage","url":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg","contentUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/08\/previdenciario-0045.jpg","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/previdenciario\/stf-relator-homologa-acordo-sobre-prazos-para-analises-de-beneficios-do-inss.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mhcalculos.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"STF: Relator homologa acordo sobre prazos para an\u00e1lises de benef\u00edcios do INSS"}]},{"@type":"WebSite","@id":"https:\/\/mhcalculos.com.br\/noticias\/#website","url":"https:\/\/mhcalculos.com.br\/noticias\/","name":"Portal de Not\u00edcias","description":"Not\u00edcias e Jurisprud\u00eancia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mhcalculos.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d","name":"Equipe MH","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","caption":"Equipe MH"}}]}},"_links":{"self":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/users\/3063"}],"replies":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7743"}],"version-history":[{"count":1,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7743\/revisions"}],"predecessor-version":[{"id":8665,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7743\/revisions\/8665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/media\/2964"}],"wp:attachment":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}