{"id":6473,"date":"2019-12-26T12:05:00","date_gmt":"2019-12-26T15:05:00","guid":{"rendered":"https:\/\/mhcalculos.com.br\/noticias\/2019\/12\/26\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo\/"},"modified":"2021-07-28T14:30:31","modified_gmt":"2021-07-28T17:30:31","slug":"tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo","status":"publish","type":"post","link":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html","title":{"rendered":"TST: Dispensa de depoimento de engenheiro gera nulidade do processo"},"content":{"rendered":"<p><br \/>\n  <\/p>\n<p ><em>Para a 2\u00aa Turma, houve cerceamento de defesa.<\/em><\/p>\n<p >26\/12\/19 &#8211; A Gest\u00e3o de Projetos e Obras Ltda. (GPO), de Salvador (BA), conseguiu anular o processo ajuizado por um engenheiro civil em raz\u00e3o do indeferimento para que fosse ouvido o depoimento do empregado na audi\u00eancia. Para a Segunda Turma do Tribunal Superior do Trabalho, houve cerceamento de defesa.<\/p>\n<p ><strong>Direito de defesa<\/strong><\/p>\n<p >Na audi\u00eancia, o juiz de primeiro grau n\u00e3o fez o interrogat\u00f3rio do engenheiro e do empregador, sob protestos da empresa. Segundo a GPO, a dispensa dos depoimentos das partes impossibilitou a obten\u00e7\u00e3o de uma poss\u00edvel confiss\u00e3o do empregado, que pretendia receber parcelas como horas extras e participa\u00e7\u00e3o nos lucros.<\/p>\n<p >O Tribunal Regional do Trabalho da 5\u00aa Regi\u00e3o (BA) manteve a senten\u00e7a, com fundamento no artigo 794 da <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/del5452.htm\">CLT<\/a>. De acordo com o dispositivo, somente haver\u00e1 nulidade dos atos praticados quando deles resultar manifesto preju\u00edzo \u00e0s partes litigantes. Para o TRT, n\u00e3o houve preju\u00edzo para ningu\u00e9m. Tendo em vista que um dos objetivos do depoimento pessoal das partes \u00e9 a obten\u00e7\u00e3o de uma poss\u00edvel confiss\u00e3o, no caso, uma n\u00e3o teve vantagem sobre a outra, pois nenhuma foi ouvida.<\/p>\n<p ><strong>Direito de obter confiss\u00e3o<\/strong><\/p>\n<p >O relator do recurso de revista, ministro Jos\u00e9 Roberto Pimenta, destacou que a empregadora tem o direito de tentar obter a confiss\u00e3o do empregado mediante a tomada de seu depoimento pessoal. Segundo o relator, o fato de o artigo 848 da CLT prever interrogat\u00f3rio das partes apenas por iniciativa do juiz n\u00e3o impede a incid\u00eancia subsidi\u00e1ria do C\u00f3digo de Processo Civil (CPC), que prev\u00ea, de forma complementar, o depoimento pessoal das partes como um dos meios de prova e de forma\u00e7\u00e3o do convencimento do julgador &#8211; \u201ce que, por isso mesmo, pode ser por elas requerido quando o juiz n\u00e3o o determinar\u201d.<\/p>\n<p >Na avalia\u00e7\u00e3o do ministro, o sistema de provas no processo do trabalho \u00e9 h\u00edbrido, composto pelas normas e provas da CLT combinadas e cumuladas com as do processo civil. Em consequ\u00eancia, os litigantes t\u00eam o direito de tentar obter a confiss\u00e3o da parte contr\u00e1ria a respeito dos fatos objeto da controv\u00e9rsia mediante o seu depoimento pessoal. \u201cTal depoimento n\u00e3o pode ser indeferido sem nenhuma fundamenta\u00e7\u00e3o pelo julgador, sob pena de cerceamento de prova e, consequentemente, nulidade da senten\u00e7a depois proferida\u201d, ressaltou.<\/p>\n<p >Por unanimidade, a Turma anulou o processo a partir da audi\u00eancia de instru\u00e7\u00e3o e determinou seu retorno \u00e0 Vara do Trabalho para que viabilize a oitiva do engenheiro conforme requerido pela empregadora.<\/p>\n<p >(LT\/CF)<\/p>\n<p >Processo: <a href=\"http:\/\/aplicacao4.tst.jus.br\/consultaProcessual\/consultaTstNumUnica.do;jsessionid=7671DAC26785F3DDDAE44A94A90B23FF.vm652?conscsjt=&amp;numeroTst=1337&amp;digitoTst=36&amp;anoTst=2015&amp;orgaoTst=5&amp;tribunalTst=05&amp;varaTst=0001&amp;consulta=Consultar\" target=\"_blank\" rel=\"noopener noreferrer\">ARR-1337-36.2015.5.05.0001<\/a><\/p>\n<p> O TST possui oito Turmas, cada uma composta de tr\u00eas ministros, com a atribui\u00e7\u00e3o de analisar recursos de revista, agravos, agravos de instrumento, agravos regimentais e recursos ordin\u00e1rios em a\u00e7\u00e3o cautelar. Das decis\u00f5es das Turmas, a parte ainda pode, em alguns casos, recorrer \u00e0 Subse\u00e7\u00e3o I Especializada em Diss\u00eddios Individuais (SBDI-1). <strong>Esta mat\u00e9ria tem cunho meramente informativo.<br \/> Permitida a reprodu\u00e7\u00e3o mediante cita\u00e7\u00e3o da fonte.<br \/> Secretaria de Comunica\u00e7\u00e3o Social<br \/> <a href=\"http:\/\/www.tst.jus.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tribunal Superior do Trabalho<\/a><br \/> Tel. (61) 3043-4907<br \/> <a href=\"mailto:secom@tst.jus.br\">secom@tst.jus.br<\/a><\/strong>       <\/br><br \/>\n<br \/><i>Com informa\u00e7\u00f5es da assessoria de imprensa do TST.<\/i><br \/>\n<br \/><a href=\"http:\/\/www.tst.jus.br\/web\/guest\/noticias?p_p_id=89Dk&#038;p_p_lifecycle=0&#038;refererPlid=10730&#038;_89Dk_struts_action=%2Fjournal_content%2Fview&#038;_89Dk_groupId=10157&#038;_89Dk_articleId=25067744\">Fonte<\/a><br \/>\n<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para a 2\u00aa Turma, houve cerceamento de defesa. 26\/12\/19 &#8211; A Gest\u00e3o de Projetos e Obras Ltda. (GPO), de Salvador (BA), conseguiu anular o processo ajuizado por um engenheiro civil em raz\u00e3o do indeferimento para que fosse ouvido o depoimento do empregado na audi\u00eancia. Para a Segunda Turma do Tribunal Superior do Trabalho, houve cerceamento [&hellip;]<\/p>\n","protected":false},"author":3063,"featured_media":1597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,21],"tags":[33,216,9,12,217,215],"class_list":{"0":"post-6473","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-trabalhista","8":"category-tst","9":"tag-calculos-trabalhistas","10":"tag-direito-trabalhista","11":"tag-pericia","12":"tag-perito","13":"tag-trabalho","14":"tag-tst"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TST: Dispensa de depoimento de engenheiro gera nulidade do processo | Portal de Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TST: Dispensa de depoimento de engenheiro gera nulidade do processo | Portal de Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Para a 2\u00aa Turma, houve cerceamento de defesa. 26\/12\/19 &#8211; A Gest\u00e3o de Projetos e Obras Ltda. (GPO), de Salvador (BA), conseguiu anular o processo ajuizado por um engenheiro civil em raz\u00e3o do indeferimento para que fosse ouvido o depoimento do empregado na audi\u00eancia. Para a Segunda Turma do Tribunal Superior do Trabalho, houve cerceamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-26T15:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-28T17:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe MH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe MH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\"},\"author\":{\"name\":\"Equipe MH\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\"},\"headline\":\"TST: Dispensa de depoimento de engenheiro gera nulidade do processo\",\"datePublished\":\"2019-12-26T15:05:00+00:00\",\"dateModified\":\"2021-07-28T17:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\"},\"wordCount\":554,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg\",\"keywords\":[\"c\u00e1lculos trabalhistas\",\"direito trabalhista\",\"per\u00edcia\",\"perito\",\"trabalho\",\"TST\"],\"articleSection\":[\"Direito Trabalhista\",\"TST\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\",\"name\":\"TST: Dispensa de depoimento de engenheiro gera nulidade do processo | Portal de Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg\",\"datePublished\":\"2019-12-26T15:05:00+00:00\",\"dateModified\":\"2021-07-28T17:30:31+00:00\",\"author\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg\",\"contentUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mhcalculos.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TST: Dispensa de depoimento de engenheiro gera nulidade do processo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#website\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/\",\"name\":\"Portal de Not\u00edcias\",\"description\":\"Not\u00edcias e Jurisprud\u00eancia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mhcalculos.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\",\"name\":\"Equipe MH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"caption\":\"Equipe MH\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TST: Dispensa de depoimento de engenheiro gera nulidade do processo | Portal de Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html","og_locale":"pt_BR","og_type":"article","og_title":"TST: Dispensa de depoimento de engenheiro gera nulidade do processo | Portal de Not\u00edcias","og_description":"Para a 2\u00aa Turma, houve cerceamento de defesa. 26\/12\/19 &#8211; A Gest\u00e3o de Projetos e Obras Ltda. (GPO), de Salvador (BA), conseguiu anular o processo ajuizado por um engenheiro civil em raz\u00e3o do indeferimento para que fosse ouvido o depoimento do empregado na audi\u00eancia. Para a Segunda Turma do Tribunal Superior do Trabalho, houve cerceamento [&hellip;]","og_url":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html","og_site_name":"Portal de Not\u00edcias","article_published_time":"2019-12-26T15:05:00+00:00","article_modified_time":"2021-07-28T17:30:31+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg","type":"image\/jpeg"}],"author":"Equipe MH","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe MH","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#article","isPartOf":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html"},"author":{"name":"Equipe MH","@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d"},"headline":"TST: Dispensa de depoimento de engenheiro gera nulidade do processo","datePublished":"2019-12-26T15:05:00+00:00","dateModified":"2021-07-28T17:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html"},"wordCount":554,"commentCount":0,"image":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage"},"thumbnailUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg","keywords":["c\u00e1lculos trabalhistas","direito trabalhista","per\u00edcia","perito","trabalho","TST"],"articleSection":["Direito Trabalhista","TST"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html","url":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html","name":"TST: Dispensa de depoimento de engenheiro gera nulidade do processo | Portal de Not\u00edcias","isPartOf":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage"},"image":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage"},"thumbnailUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg","datePublished":"2019-12-26T15:05:00+00:00","dateModified":"2021-07-28T17:30:31+00:00","author":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d"},"breadcrumb":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#primaryimage","url":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg","contentUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0037.jpg","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-dispensa-de-depoimento-de-engenheiro-gera-nulidade-do-processo.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mhcalculos.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"TST: Dispensa de depoimento de engenheiro gera nulidade do processo"}]},{"@type":"WebSite","@id":"https:\/\/mhcalculos.com.br\/noticias\/#website","url":"https:\/\/mhcalculos.com.br\/noticias\/","name":"Portal de Not\u00edcias","description":"Not\u00edcias e Jurisprud\u00eancia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mhcalculos.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d","name":"Equipe MH","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","caption":"Equipe MH"}}]}},"_links":{"self":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/users\/3063"}],"replies":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6473"}],"version-history":[{"count":1,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6473\/revisions"}],"predecessor-version":[{"id":9454,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6473\/revisions\/9454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/media\/1597"}],"wp:attachment":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}