{"id":6408,"date":"2019-12-02T17:28:00","date_gmt":"2019-12-02T20:28:00","guid":{"rendered":"https:\/\/mhcalculos.com.br\/noticias\/2019\/12\/02\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho\/"},"modified":"2021-07-28T14:30:40","modified_gmt":"2021-07-28T17:30:40","slug":"tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho","status":"publish","type":"post","link":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html","title":{"rendered":"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho"},"content":{"rendered":"<p><br \/>\n  <\/p>\n<p ><em>Os transtornos surgiram ap\u00f3s ele ser atropelado em dia de folga.<\/em><\/p>\n<p >02\/12\/19 &#8211; A Quinta Turma do Tribunal Superior do Trabalho considerou indevida a reintegra\u00e7\u00e3o no emprego de um mec\u00e2nico que prestava servi\u00e7os para a Vale S. A. diagnosticado com transtorno psiqui\u00e1trico. Segundo a Turma, os elementos do caso n\u00e3o permitem concluir que ele estava incapacitado para o trabalho no momento da dispensa.<\/p>\n<p ><strong>Atropelamento<\/strong><\/p>\n<p >O mec\u00e2nico, que tinha de fazer uso de medica\u00e7\u00e3o cont\u00ednua em raz\u00e3o da doen\u00e7a, ficou afastado por aux\u00edlio-doen\u00e7a depois de ter sido atropelado num dia de folga. Em raz\u00e3o do acidente, disse que desenvolveu problemas psiqui\u00e1tricos que exigiam o uso cont\u00ednuo de \u201cmedica\u00e7\u00e3o fort\u00edssima\u201d.<\/p>\n<p >Embora tenha sido considerado apto ao servi\u00e7o ap\u00f3s a alta do INSS, o m\u00e9dico psiquiatra registrou a necessidade de manuten\u00e7\u00e3o de tratamento ambulatorial e de restri\u00e7\u00e3o para atividades em lugares altos e em espa\u00e7os confinados. Uma semana depois do retorno, a empresa rescindiu unilateralmente o contrato de trabalho.<\/p>\n<p >Na reclama\u00e7\u00e3o trabalhista, o mec\u00e2nico sustentava que, apesar de n\u00e3o se tratar de acidente de trabalho, ele fora dispensado sem aptid\u00e3o plena para o trabalho.<\/p>\n<p ><strong>Inaptid\u00e3o<\/strong><\/p>\n<p >O pedido de reintegra\u00e7\u00e3o foi julgado improcedente pelo ju\u00edzo da 9\u00aa Vara do Trabalho de Vit\u00f3ria (ES). Por\u00e9m, o Tribunal Regional do Trabalho da 17\u00aa Regi\u00e3o declarou nula a rescis\u00e3o e considerou suspenso o contrato de trabalho, em raz\u00e3o da inaptid\u00e3o do empregado.&nbsp;<\/p>\n<p ><strong>Conclus\u00e3o diversa<\/strong><\/p>\n<p >Embora tenha considerado como verdadeiros os fatos descritos pelo Tribunal Regional, a Quinta Turma do TST chegou a conclus\u00e3o inteiramente diversa. Para o colegiado, o fim da incapacidade foi devidamente provado, pois v\u00e1rios pedidos de extens\u00e3o do benef\u00edcio previdenci\u00e1rio haviam sido negados ao empregado.<\/p>\n<p >O relator do recurso de revista da Vale, ministro Breno Medeiros, observou tamb\u00e9m que a m\u00e9dica da empresa havia atestado a capacidade do mec\u00e2nico para o trabalho, ainda que com restri\u00e7\u00f5es para algumas atividades. \u201cNesse contexto, os elementos f\u00e1ticos descritos na decis\u00e3o do TRT n\u00e3o viabilizam a conclus\u00e3o de que o empregado estava incapacitado para o trabalho no momento da rescis\u00e3o contratual, de modo a ensejar a nulidade do ato\u201d, afirmou.<\/p>\n<p >Ainda segundo o relator, as limita\u00e7\u00f5es parciais para o desempenho de algumas atividades sequer foram reconhecidas pelo INSS como incapacitantes e, portanto, n\u00e3o s\u00e3o suficientes para retirar do empregador o direito \u00e0 rescis\u00e3o contratual. O fato de a doen\u00e7a n\u00e3o ter qualquer nexo com o trabalho, a seu ver, afasta a ocorr\u00eancia de dispensa discriminat\u00f3ria.<\/p>\n<p >(GL\/CF)<\/p>\n<p >Processo: <a href=\"http:\/\/aplicacao5.tst.jus.br\/consultaProcessual\/resumoForm.do?consulta=1&amp;numeroInt=291934&amp;anoInt=2015\" target=\"_blank\" rel=\"noopener noreferrer\">RR-77800-64.2012.5.17.0009<\/a><\/p>\n<p> O TST possui oito Turmas julgadoras, cada uma composta por tr\u00eas ministros, com a atribui\u00e7\u00e3o de analisar recursos de revista, agravos, agravos de instrumento, agravos regimentais e recursos ordin\u00e1rios em a\u00e7\u00e3o cautelar. Das decis\u00f5es das Turmas, a parte ainda pode, em alguns casos, recorrer \u00e0 Subse\u00e7\u00e3o I Especializada em Diss\u00eddios Individuais (SBDI-1). <strong>Esta mat\u00e9ria tem car\u00e1ter informativo, sem cunho oficial.<br \/> Permitida a reprodu\u00e7\u00e3o mediante cita\u00e7\u00e3o da fonte.<br \/> Secretaria de Comunica\u00e7\u00e3o Social<br \/> <a href=\"http:\/\/www.tst.jus.br\" target=\"_blank\" rel=\"noopener noreferrer\">Tribunal Superior do Trabalho<\/a><br \/> Tel. (61) 3043-4907<br \/> <a href=\"mailto:secom@tst.jus.br\" >secom@tst.jus.br<\/a><\/strong>       <\/br><br \/>\n<br \/><i>Com informa\u00e7\u00f5es da assessoria de imprensa do TST.<\/i><br \/>\n<br \/><a href=\"http:\/\/www.tst.jus.br\/web\/guest\/noticias?p_p_id=89Dk&#038;p_p_lifecycle=0&#038;refererPlid=10730&#038;_89Dk_struts_action=%2Fjournal_content%2Fview&#038;_89Dk_groupId=10157&#038;_89Dk_articleId=25051238\">Fonte<\/a><br \/>\n<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os transtornos surgiram ap\u00f3s ele ser atropelado em dia de folga. 02\/12\/19 &#8211; A Quinta Turma do Tribunal Superior do Trabalho considerou indevida a reintegra\u00e7\u00e3o no emprego de um mec\u00e2nico que prestava servi\u00e7os para a Vale S. A. diagnosticado com transtorno psiqui\u00e1trico. Segundo a Turma, os elementos do caso n\u00e3o permitem concluir que ele estava [&hellip;]<\/p>\n","protected":false},"author":3063,"featured_media":1603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,21],"tags":[33,216,9,12,217,215],"class_list":{"0":"post-6408","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-trabalhista","8":"category-tst","9":"tag-calculos-trabalhistas","10":"tag-direito-trabalhista","11":"tag-pericia","12":"tag-perito","13":"tag-trabalho","14":"tag-tst"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho | Portal de Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho | Portal de Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Os transtornos surgiram ap\u00f3s ele ser atropelado em dia de folga. 02\/12\/19 &#8211; A Quinta Turma do Tribunal Superior do Trabalho considerou indevida a reintegra\u00e7\u00e3o no emprego de um mec\u00e2nico que prestava servi\u00e7os para a Vale S. A. diagnosticado com transtorno psiqui\u00e1trico. Segundo a Turma, os elementos do caso n\u00e3o permitem concluir que ele estava [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-02T20:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-28T17:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe MH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe MH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\"},\"author\":{\"name\":\"Equipe MH\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\"},\"headline\":\"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho\",\"datePublished\":\"2019-12-02T20:28:00+00:00\",\"dateModified\":\"2021-07-28T17:30:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\"},\"wordCount\":581,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg\",\"keywords\":[\"c\u00e1lculos trabalhistas\",\"direito trabalhista\",\"per\u00edcia\",\"perito\",\"trabalho\",\"TST\"],\"articleSection\":[\"Direito Trabalhista\",\"TST\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\",\"name\":\"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho | Portal de Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg\",\"datePublished\":\"2019-12-02T20:28:00+00:00\",\"dateModified\":\"2021-07-28T17:30:40+00:00\",\"author\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg\",\"contentUrl\":\"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mhcalculos.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#website\",\"url\":\"https:\/\/mhcalculos.com.br\/noticias\/\",\"name\":\"Portal de Not\u00edcias\",\"description\":\"Not\u00edcias e Jurisprud\u00eancia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mhcalculos.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d\",\"name\":\"Equipe MH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g\",\"caption\":\"Equipe MH\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho | Portal de Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html","og_locale":"pt_BR","og_type":"article","og_title":"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho | Portal de Not\u00edcias","og_description":"Os transtornos surgiram ap\u00f3s ele ser atropelado em dia de folga. 02\/12\/19 &#8211; A Quinta Turma do Tribunal Superior do Trabalho considerou indevida a reintegra\u00e7\u00e3o no emprego de um mec\u00e2nico que prestava servi\u00e7os para a Vale S. A. diagnosticado com transtorno psiqui\u00e1trico. Segundo a Turma, os elementos do caso n\u00e3o permitem concluir que ele estava [&hellip;]","og_url":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html","og_site_name":"Portal de Not\u00edcias","article_published_time":"2019-12-02T20:28:00+00:00","article_modified_time":"2021-07-28T17:30:40+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg","type":"image\/jpeg"}],"author":"Equipe MH","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe MH","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#article","isPartOf":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html"},"author":{"name":"Equipe MH","@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d"},"headline":"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho","datePublished":"2019-12-02T20:28:00+00:00","dateModified":"2021-07-28T17:30:40+00:00","mainEntityOfPage":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html"},"wordCount":581,"commentCount":0,"image":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage"},"thumbnailUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg","keywords":["c\u00e1lculos trabalhistas","direito trabalhista","per\u00edcia","perito","trabalho","TST"],"articleSection":["Direito Trabalhista","TST"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html","url":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html","name":"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho | Portal de Not\u00edcias","isPartOf":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage"},"image":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage"},"thumbnailUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg","datePublished":"2019-12-02T20:28:00+00:00","dateModified":"2021-07-28T17:30:40+00:00","author":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d"},"breadcrumb":{"@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#primaryimage","url":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg","contentUrl":"https:\/\/mhcalculos.com.br\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/trabalhista-0025.jpg","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mhcalculos.com.br\/noticias\/area\/trabalhista\/tst-negada-a-reintegracao-de-mecanico-com-doenca-psiquiatrica-nao-relacionada-ao-trabalho.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mhcalculos.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"TST: Negada a reintegra\u00e7\u00e3o de mec\u00e2nico com doen\u00e7a psiqui\u00e1trica n\u00e3o relacionada ao trabalho"}]},{"@type":"WebSite","@id":"https:\/\/mhcalculos.com.br\/noticias\/#website","url":"https:\/\/mhcalculos.com.br\/noticias\/","name":"Portal de Not\u00edcias","description":"Not\u00edcias e Jurisprud\u00eancia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mhcalculos.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/mhcalculos.com.br\/noticias\/#\/schema\/person\/88d1c34bf72dc779ea14a5a6b8e0ae8d","name":"Equipe MH","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de1c686c2ecc9c5a3f327e3431d819eb39f8f05d4e1045f5a1caad6daaba987f?s=96&d=mm&r=g","caption":"Equipe MH"}}]}},"_links":{"self":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/users\/3063"}],"replies":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6408"}],"version-history":[{"count":1,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6408\/revisions"}],"predecessor-version":[{"id":9503,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6408\/revisions\/9503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/media\/1603"}],"wp:attachment":[{"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mhcalculos.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}